{"id":1829,"date":"2017-06-11T09:06:54","date_gmt":"2017-06-11T07:06:54","guid":{"rendered":"http:\/\/glam-magazine.com\/?p=666"},"modified":"2017-06-11T09:06:54","modified_gmt":"2017-06-11T07:06:54","slug":"die-sommerfrucht-melone","status":"publish","type":"post","link":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/","title":{"rendered":"Die Sommerfrucht Melone"},"content":{"rendered":"<h2>Ob als Snack f\u00fcr Zwischendurch, als Smoothie oder Eis \u2013 die Melone z\u00e4hlt zu den beliebtesten Sommerfr\u00fcchten und ist sehr vielseitig.<\/h2>\n<p>Sie punktet besonders mit ihrem hohen Wasser- und niedrigen Kaloriengehalt: Eine gro\u00dfe Portion von 250g der s\u00fc\u00dfen Frucht enth\u00e4lt weniger als 100 Kilokalorien, deckt etwa die H\u00e4lfte der empfohlenen Tageszufuhr an Pantothens\u00e4ure und fungiert zudem als Durstl\u00f6scher an hei\u00dfen Sommertagen. Jedoch handelt es sich bei der Melone um keine Obstsorte, sondern um ein Fruchtgem\u00fcse \u2013 botanisch gesehen ist sie ein K\u00fcrbisgew\u00e4chs. Dabei wird zwischen Wasser- und Zuckermelone unterschieden, wovon es weltweit mehr als 750 verschiedener Sorten gibt. Die Zuckermelonen sind aromatischer, beide Sorten aber liefern diverse Vitamine, wie das Provitamin A Beta-Carotin, Vitamin C und Fols\u00e4ure.<\/p>\n<h3><strong>Die Wassermelone<\/strong><\/h3>\n<p>Der Klassiker unter den Sorten ist die Wassermelone und schmeckt besonders als Smoothie, Snack oder im Salat. Sie wiegt meist zwischen zwei und f\u00fcnf Kilo, ist an der Oberfl\u00e4che hell- bis dunkelgr\u00fcn und innen rot. Da sie zu 95% aus Wasser besteht, ist sie mit knapp 25 Kilokalorien pro 100g die kalorien\u00e4rmste Melone. Auf Grund ihrer Frische und S\u00fc\u00dfe ist sie die optimale Frucht f\u00fcr Getr\u00e4nke, wie Cocktails und Eis.<\/p>\n<h3><strong>Die Honigmelone<\/strong><\/h3>\n<p>Die Honigmelone geh\u00f6rt zu den Zuckermelonen, ist au\u00dfen sonnengelb, innerlich gr\u00fcn-wei\u00df und hat eher die ovale Form eines Footballs. F\u00fcr gew\u00f6hnlich wiegt sie ein bis drei Kilo und ist somit leichter als die Wassermelone. Die Honigmelone eignet sich besonders f\u00fcr den puren Genuss oder wird als Vorspeise mit Schinken genossen. Zudem verf\u00fcgt sie \u00fcber einen hohen Vitamin E-Gehalt, weshalb sie sich p\u00fcriert sogar als eine sommerliche Gesichtsmaske empfiehlt. Ihr Aroma ist, wie bereits erw\u00e4hnt, sehr frisch und s\u00fc\u00df, weshalb sie auch etwa doppelt so viele Kilokalorien enth\u00e4lt wie die Wassermelone.<\/p>\n<h3><strong>Reife Melone?<\/strong><\/h3>\n<p>Reife Melonen sind an ihrem Klang, ihrem angenehm s\u00fc\u00dfen Geruch und bei leichtem Druck am Stielende zu erkennen. Dabei wird mit einem Finger auf die Schale geklopft, woraufhin ein voller und tiefer Ton erklingen sollte. Ist die Melone unreif, wird sie zum ungew\u00fcnschten Abf\u00fchrmittel.\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ob als Snack f\u00fcr Zwischendurch, als Smoothie oder Eis \u2013 die Melone z\u00e4hlt zu den beliebtesten Sommerfr\u00fcchten und ist sehr vielseitig. Sie punktet besonders mit ihrem hohen Wasser- und niedrigen Kaloriengehalt: Eine gro\u00dfe Portion von 250g der s\u00fc\u00dfen Frucht enth\u00e4lt weniger als 100 Kilokalorien, deckt etwa die H\u00e4lfte der empfohlenen Tageszufuhr an Pantothens\u00e4ure und fungiert [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[73],"tags":[360,361,362],"class_list":["post-1829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food_drink","tag-honigmelone","tag-melone","tag-wassermelone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Sommerfrucht Melone - Wellnessbase.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Sommerfrucht Melone - Wellnessbase.de\" \/>\n<meta property=\"og:description\" content=\"Ob als Snack f\u00fcr Zwischendurch, als Smoothie oder Eis \u2013 die Melone z\u00e4hlt zu den beliebtesten Sommerfr\u00fcchten und ist sehr vielseitig. Sie punktet besonders mit ihrem hohen Wasser- und niedrigen Kaloriengehalt: Eine gro\u00dfe Portion von 250g der s\u00fc\u00dfen Frucht enth\u00e4lt weniger als 100 Kilokalorien, deckt etwa die H\u00e4lfte der empfohlenen Tageszufuhr an Pantothens\u00e4ure und fungiert [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/\" \/>\n<meta property=\"og:site_name\" content=\"Wellnessbase.de\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-11T07:06:54+00:00\" \/>\n<meta name=\"author\" content=\"editors@12werk.de\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"editors@12werk.de\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/\"},\"author\":{\"name\":\"editors@12werk.de\",\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/#\\\/schema\\\/person\\\/8456c135f5a25d177a2ea6e1cb865855\"},\"headline\":\"Die Sommerfrucht Melone\",\"datePublished\":\"2017-06-11T07:06:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/\"},\"wordCount\":358,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Honigmelone\",\"Melone\",\"Wassermelone\"],\"articleSection\":[\"Food &amp; Drink\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/\",\"url\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/\",\"name\":\"Die Sommerfrucht Melone - Wellnessbase.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-06-11T07:06:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/#\\\/schema\\\/person\\\/8456c135f5a25d177a2ea6e1cb865855\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/die-sommerfrucht-melone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Sommerfrucht Melone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/#website\",\"url\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/\",\"name\":\"Wellnessbase.de\",\"description\":\"Der Shop rund um Wellness\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wellnessbase.de\\\/shop\\\/#\\\/schema\\\/person\\\/8456c135f5a25d177a2ea6e1cb865855\",\"name\":\"editors@12werk.de\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a1e7b8ed43036922329ec02a0fd21d5e489c44841fc9f04d0d438d4da8da57f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a1e7b8ed43036922329ec02a0fd21d5e489c44841fc9f04d0d438d4da8da57f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a1e7b8ed43036922329ec02a0fd21d5e489c44841fc9f04d0d438d4da8da57f?s=96&d=mm&r=g\",\"caption\":\"editors@12werk.de\"},\"sameAs\":[\"http:\\\/\\\/wellnessbase.de\\\/shop\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Sommerfrucht Melone - Wellnessbase.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/","og_locale":"de_DE","og_type":"article","og_title":"Die Sommerfrucht Melone - Wellnessbase.de","og_description":"Ob als Snack f\u00fcr Zwischendurch, als Smoothie oder Eis \u2013 die Melone z\u00e4hlt zu den beliebtesten Sommerfr\u00fcchten und ist sehr vielseitig. Sie punktet besonders mit ihrem hohen Wasser- und niedrigen Kaloriengehalt: Eine gro\u00dfe Portion von 250g der s\u00fc\u00dfen Frucht enth\u00e4lt weniger als 100 Kilokalorien, deckt etwa die H\u00e4lfte der empfohlenen Tageszufuhr an Pantothens\u00e4ure und fungiert [&hellip;]","og_url":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/","og_site_name":"Wellnessbase.de","article_published_time":"2017-06-11T07:06:54+00:00","author":"editors@12werk.de","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"editors@12werk.de","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/#article","isPartOf":{"@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/"},"author":{"name":"editors@12werk.de","@id":"https:\/\/www.wellnessbase.de\/shop\/#\/schema\/person\/8456c135f5a25d177a2ea6e1cb865855"},"headline":"Die Sommerfrucht Melone","datePublished":"2017-06-11T07:06:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/"},"wordCount":358,"commentCount":0,"image":{"@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/#primaryimage"},"thumbnailUrl":"","keywords":["Honigmelone","Melone","Wassermelone"],"articleSection":["Food &amp; Drink"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/","url":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/","name":"Die Sommerfrucht Melone - Wellnessbase.de","isPartOf":{"@id":"https:\/\/www.wellnessbase.de\/shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/#primaryimage"},"image":{"@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-06-11T07:06:54+00:00","author":{"@id":"https:\/\/www.wellnessbase.de\/shop\/#\/schema\/person\/8456c135f5a25d177a2ea6e1cb865855"},"breadcrumb":{"@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.wellnessbase.de\/shop\/die-sommerfrucht-melone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.wellnessbase.de\/shop\/"},{"@type":"ListItem","position":2,"name":"Die Sommerfrucht Melone"}]},{"@type":"WebSite","@id":"https:\/\/www.wellnessbase.de\/shop\/#website","url":"https:\/\/www.wellnessbase.de\/shop\/","name":"Wellnessbase.de","description":"Der Shop rund um Wellness","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wellnessbase.de\/shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.wellnessbase.de\/shop\/#\/schema\/person\/8456c135f5a25d177a2ea6e1cb865855","name":"editors@12werk.de","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4a1e7b8ed43036922329ec02a0fd21d5e489c44841fc9f04d0d438d4da8da57f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a1e7b8ed43036922329ec02a0fd21d5e489c44841fc9f04d0d438d4da8da57f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a1e7b8ed43036922329ec02a0fd21d5e489c44841fc9f04d0d438d4da8da57f?s=96&d=mm&r=g","caption":"editors@12werk.de"},"sameAs":["http:\/\/wellnessbase.de\/shop"]}]}},"_links":{"self":[{"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/wp\/v2\/posts\/1829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/wp\/v2\/comments?post=1829"}],"version-history":[{"count":0,"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/wp\/v2\/posts\/1829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/wp\/v2\/media?parent=1829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/wp\/v2\/categories?post=1829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wellnessbase.de\/shop\/wp-json\/wp\/v2\/tags?post=1829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}